{"id":4292,"date":"2020-06-01T18:14:00","date_gmt":"2020-06-01T21:14:00","guid":{"rendered":"http:\/\/www.lateandes.com\/?p=4292"},"modified":"2020-10-01T18:19:36","modified_gmt":"2020-10-01T21:19:36","slug":"la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta","status":"publish","type":"post","link":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/","title":{"rendered":"LA.TE. ANDES S.A. en la Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica para el Desarrollo Productivo de Salta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El d\u00eda 26 de mayo de 2020, en la Provincia de Salta, mediante el Decreto Provincial N\u00b0 302\/2020, se cre\u00f3 la Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica de la Provincia de Salta, con el objetivo de fomentar y contribuir a la incorporaci\u00f3n y el desarrollo de la ciencia, la tecnolog\u00eda y la innovaci\u00f3n en las actividades productivas, y en las pol\u00edticas educativas y de investigaci\u00f3n. Este organismo, generado bajo la \u00f3rbita de la Estructura Org\u00e1nica del Ministerio de Educaci\u00f3n, Cultura, Ciencia y Tecnolog\u00eda, tendr\u00e1 las siguientes funciones y atribuciones:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Gestionar fondos espec\u00edficos de organismos nacionales e internacionales para proyectos de desarrollo cient\u00edfico, transferencia de tecnolog\u00eda y de innovaci\u00f3n productiva.<\/li><li>Centralizar la vinculaci\u00f3n del Ejecutivo Provincial con el Ministerio de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n de la Naci\u00f3n y la Agencia Nacional de Promoci\u00f3n Cient\u00edfica y Tecnol\u00f3gica.<\/li><li>Orientar la investigaci\u00f3n cient\u00edfica y la innovaci\u00f3n tecnol\u00f3gica a su aplicaci\u00f3n pr\u00e1ctica y efectiva en el \u00e1mbito de la producci\u00f3n y la educaci\u00f3n vinculando los sectores acad\u00e9micos y cient\u00edficos a las instituciones productivas.<\/li><li>Difundir los conocimientos cient\u00edficos y tecnol\u00f3gicos entre diversos sectores de la sociedad e instalar el valor de la cultura cient\u00edfica como camino para el desarrollo.<\/li><li>Detectar necesidades concretas de tecnolog\u00edas para potenciar el desarrollo de la Provincia.<\/li><li>Establecer acciones y pol\u00edticas que favorezcan la incorporaci\u00f3n de la ciencia y la tecnolog\u00eda en el ecosistema emprendedor.<\/li><li>Colaborar en el desarrollo de proyectos cient\u00edficos de envergadura para la Provincia.<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">La Agencia mencionada est\u00e1 integrada por un Director, un Vicedirector y un Consejo Asesor compuesto por representantes gubernamentales, entidades acad\u00e9micas universitarias, institutos nacionales, fundaciones y representantes de empresas. En la categor\u00eda de empresas, se encuentra representada LA.TE ANDES Grupo Empresario Salte\u00f1o GEOMAP\/CONICET a trav\u00e9s de su Presidente, el Lic. Roberto Hern\u00e1ndez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 26 de mayo de 2020, en la Provincia de Salta, mediante el Decreto Provincial N\u00b0 302\/2020, se cre\u00f3 la Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica de la Provincia de Salta, con el objetivo de fomentar y contribuir a la incorporaci\u00f3n y el desarrollo de la ciencia, la tecnolog\u00eda y la innovaci\u00f3n en&#8230;<\/p>\n","protected":false},"author":18,"featured_media":4294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[104],"class_list":["post-4292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-agencia-de-promocion-cientifica-e-innovacion-tecnologica-de-la-provincia-de-salta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA.TE. ANDES S.A. en la Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica para el Desarrollo Productivo de Salta - LA.TE. ANDES S.A.<\/title>\n<meta name=\"description\" content=\"LA.TE. ANDES S.A. representada en la reci\u00e9n creada Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica de la Provincia de Salta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA.TE. ANDES S.A. en la Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica para el Desarrollo Productivo de Salta - LA.TE. ANDES S.A.\" \/>\n<meta property=\"og:description\" content=\"LA.TE. ANDES S.A. representada en la reci\u00e9n creada Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica de la Provincia de Salta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/\" \/>\n<meta property=\"og:site_name\" content=\"LA.TE. ANDES S.A.\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-01T21:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-01T21:19:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lateandes.com\/late\/wp-content\/uploads\/2020\/10\/agencia-de-promocion-cientifica-e-innovacion-tecnologica-de-la-provincia-de-salta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prensa La.Te. Andes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prensa La.Te. Andes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA.TE. ANDES S.A. en la Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica para el Desarrollo Productivo de Salta - LA.TE. ANDES S.A.","description":"LA.TE. ANDES S.A. representada en la reci\u00e9n creada Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica de la Provincia de Salta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/","og_locale":"en_US","og_type":"article","og_title":"LA.TE. ANDES S.A. en la Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica para el Desarrollo Productivo de Salta - LA.TE. ANDES S.A.","og_description":"LA.TE. ANDES S.A. representada en la reci\u00e9n creada Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica de la Provincia de Salta.","og_url":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/","og_site_name":"LA.TE. ANDES S.A.","article_published_time":"2020-06-01T21:14:00+00:00","article_modified_time":"2020-10-01T21:19:36+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.lateandes.com\/late\/wp-content\/uploads\/2020\/10\/agencia-de-promocion-cientifica-e-innovacion-tecnologica-de-la-provincia-de-salta.jpg","type":"image\/jpeg"}],"author":"Prensa La.Te. Andes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Prensa La.Te. Andes","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/#article","isPartOf":{"@id":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/"},"author":{"name":"Prensa La.Te. Andes","@id":"https:\/\/www.lateandes.com\/en\/#\/schema\/person\/884dcfb7ca3382fb26fecb065725ef46"},"headline":"LA.TE. ANDES S.A. en la Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica para el Desarrollo Productivo de Salta","datePublished":"2020-06-01T21:14:00+00:00","dateModified":"2020-10-01T21:19:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/"},"wordCount":357,"publisher":{"@id":"https:\/\/www.lateandes.com\/en\/#organization"},"image":{"@id":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lateandes.com\/late\/wp-content\/uploads\/2020\/10\/agencia-de-promocion-cientifica-e-innovacion-tecnologica-de-la-provincia-de-salta.jpg","keywords":["Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica de la Provincia de Salta"],"articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/","url":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/","name":"LA.TE. ANDES S.A. en la Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica para el Desarrollo Productivo de Salta - LA.TE. ANDES S.A.","isPartOf":{"@id":"https:\/\/www.lateandes.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/#primaryimage"},"image":{"@id":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lateandes.com\/late\/wp-content\/uploads\/2020\/10\/agencia-de-promocion-cientifica-e-innovacion-tecnologica-de-la-provincia-de-salta.jpg","datePublished":"2020-06-01T21:14:00+00:00","dateModified":"2020-10-01T21:19:36+00:00","description":"LA.TE. ANDES S.A. representada en la reci\u00e9n creada Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica de la Provincia de Salta.","breadcrumb":{"@id":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/#primaryimage","url":"https:\/\/www.lateandes.com\/late\/wp-content\/uploads\/2020\/10\/agencia-de-promocion-cientifica-e-innovacion-tecnologica-de-la-provincia-de-salta.jpg","contentUrl":"https:\/\/www.lateandes.com\/late\/wp-content\/uploads\/2020\/10\/agencia-de-promocion-cientifica-e-innovacion-tecnologica-de-la-provincia-de-salta.jpg","width":960,"height":640,"caption":"Videoconferencia inaugural de la Agencia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lateandes.com\/en\/la-te-andes-s-a-en-la-agencia-de-promocion-cientifica-e-innovacion-tecnologica-para-el-desarrollo-productivo-de-salta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lateandes.com\/en\/"},{"@type":"ListItem","position":2,"name":"LA.TE. ANDES S.A. en la Agencia de Promoci\u00f3n Cient\u00edfica e Innovaci\u00f3n Tecnol\u00f3gica para el Desarrollo Productivo de Salta"}]},{"@type":"WebSite","@id":"https:\/\/www.lateandes.com\/en\/#website","url":"https:\/\/www.lateandes.com\/en\/","name":"LA.TE. ANDES S.A.","description":"Geo-thermochronology Lab","publisher":{"@id":"https:\/\/www.lateandes.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lateandes.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.lateandes.com\/en\/#organization","name":"LA.TE. ANDES S.A.","url":"https:\/\/www.lateandes.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lateandes.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.lateandes.com\/late\/wp-content\/uploads\/2024\/05\/logo-lateandes-redes-iso-ALT.jpg","contentUrl":"https:\/\/www.lateandes.com\/late\/wp-content\/uploads\/2024\/05\/logo-lateandes-redes-iso-ALT.jpg","width":512,"height":512,"caption":"LA.TE. ANDES S.A."},"image":{"@id":"https:\/\/www.lateandes.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.lateandes.com\/en\/#\/schema\/person\/884dcfb7ca3382fb26fecb065725ef46","name":"Prensa La.Te. Andes","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/62294bb15c68195f20fadd3d4b4b870c013318441514478bf12fcd3fc56fa649?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/62294bb15c68195f20fadd3d4b4b870c013318441514478bf12fcd3fc56fa649?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62294bb15c68195f20fadd3d4b4b870c013318441514478bf12fcd3fc56fa649?s=96&d=mm&r=g","caption":"Prensa La.Te. Andes"}}]}},"_links":{"self":[{"href":"https:\/\/www.lateandes.com\/en\/wp-json\/wp\/v2\/posts\/4292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lateandes.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lateandes.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lateandes.com\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lateandes.com\/en\/wp-json\/wp\/v2\/comments?post=4292"}],"version-history":[{"count":1,"href":"https:\/\/www.lateandes.com\/en\/wp-json\/wp\/v2\/posts\/4292\/revisions"}],"predecessor-version":[{"id":4293,"href":"https:\/\/www.lateandes.com\/en\/wp-json\/wp\/v2\/posts\/4292\/revisions\/4293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lateandes.com\/en\/wp-json\/wp\/v2\/media\/4294"}],"wp:attachment":[{"href":"https:\/\/www.lateandes.com\/en\/wp-json\/wp\/v2\/media?parent=4292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lateandes.com\/en\/wp-json\/wp\/v2\/categories?post=4292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lateandes.com\/en\/wp-json\/wp\/v2\/tags?post=4292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}